{"id":62251,"date":"2018-01-07T02:13:04","date_gmt":"2018-01-07T05:13:04","guid":{"rendered":"https:\/\/www.dicaseducacaofisica.info\/regras-voleibol\/"},"modified":"2020-10-25T03:23:06","modified_gmt":"2020-10-25T06:23:06","slug":"regras-voleibol","status":"publish","type":"post","link":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/","title":{"rendered":"Regras do VOLEIBOL Ilustradas"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Introducao_Regras_do_Voleibol\" >Introdu\u00e7\u00e3o: Regras do Voleibol<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Que_tamanho_do_campo_de_Voleibol\" >Que tamanho do campo de Voleibol?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Qual_a_altura_da_rede_de_voleibol\" >Qual a altura da rede de voleibol?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Quantos_jogadores_tem_uma_equipa_de_Voleibol\" >Quantos jogadores t\u00eam uma equipa de Voleibol<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Marcacao_de_Pontos_no_Voleibol\" >Marca\u00e7\u00e3o de Pontos no Voleibol<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#O_que_e_Jogada_no_Voleibol\" >O que \u00e9 Jogada no Voleibol?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Quantos_Sets_tem_um_jogo_de_Voleibol\" >Quantos Sets tem um jogo de Voleibol?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Sobre_Sorteio_formacao_inicial_da_equipa_e_posicao_dos_jogadores_no_voleibol\" >Sobre Sorteio, forma\u00e7\u00e3o inicial da equipa e posi\u00e7\u00e3o dos jogadores no voleibol<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Sorteio\" >Sorteio<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Equipa_de_Voleibol\" >Equipa de Voleibol<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Posicoes_e_Rotacao_no_Voleibol\" >Posi\u00e7\u00f5es e Rota\u00e7\u00e3o no Voleibol<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Como_e_feita_Rotacao_no_Voleibol\" >Como \u00e9 feita Rota\u00e7\u00e3o no Voleibol?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Faltas_de_Rotacao_no_Voleibol\" >Faltas de Rota\u00e7\u00e3o no Voleibol<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Bola_fora_e_Toques_na_bola_no_Voleibol\" >Bola fora e Toques na bola no Voleibol<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#A_bola_e_considerada_fora_de_jogo_quando\" >A bola \u00e9 considerada fora de jogo quando:<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Toques_da_Equipa_na_bola\" >Toques da Equipa na bola<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Dois_Toques\" >Dois Toques<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Bola_Retida\" >Bola Retida<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Invasao_sobre_a_Rede_no_Voleibol\" >Invas\u00e3o sobre a Rede no Voleibol<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Invasao_sob_a_Rede\" >Invas\u00e3o sob a Rede<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Contacto_com_a_Rede_de_Voleibol_Toque_na_rede\" >Contacto com a Rede de Voleibol (Toque na rede)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Sobre_o_Servico_no_Voleibol\" >Sobre o Servi\u00e7o no Voleibol<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Servico_e_faltas_de_Servico\" >Servi\u00e7o e faltas de Servi\u00e7o<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Sao_Faltas_de_Ataque_no_voleibol\" >S\u00e3o Faltas de Ataque no voleibol:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Sao_faltas_do_Bloco_de_Voleibol\" >S\u00e3o faltas do Bloco de Voleibol:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Pedido_de_Tempo_e_Substituicoes_no_Voleibol\" >Pedido de Tempo e Substitui\u00e7\u00f5es no Voleibol<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Pausas_e_mudanca_de_Campo_no_Voleibol\" >Pausas e mudan\u00e7a de Campo no Voleibol<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Regras_para_o_voleibol_libero\" >Regras para o voleibol libero:<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Video_sobre_as_regras_do_voleibol\" >V\u00eddeo sobre as regras do voleibol<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/#Mais_conteudo_de_voleibol\" >Mais conte\u00fado de voleibol<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Introducao_Regras_do_Voleibol\"><\/span>Introdu\u00e7\u00e3o: Regras do Voleibol<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Descubra todas as regras do <a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/modalidades-desportes\/voleibol-pt-pt\/\" target=\"_blank\" rel=\"noopener noreferrer\">Voleibol<\/a> e tire todas as suas d\u00favidas com esse artigo ilustrado e explicativo que o <a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/\" target=\"_blank\" rel=\"noopener noreferrer\">Blog Dicas Educa\u00e7\u00e3o F\u00edsica<\/a> preparou com muito carinho para voc\u00ea que gosta de jogar Voleibol. Chega de conte\u00fado raso que n\u00e3o explicada quase nada, aqui, voc\u00ea vai aprender todas as regras que regem o jogo de Voleibol.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Que_tamanho_do_campo_de_Voleibol\"><\/span>Que tamanho do campo de Voleibol?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>O campo de Voleibol \u00e9 um ret\u00e2ngulo que mede 18 metros de comprimento por 9 metros de largura. As linhas do tribunal t\u00eam 5 cent\u00edmetros de largura.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Qual_a_altura_da_rede_de_voleibol\"><\/span>Qual a altura da rede de voleibol?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>A Rede de Voleibol tem uma altura de 2,24 metros para jogos femininos e 2,43 metros para jogos masculinos<\/li>\n<li>Os postes t\u00eam 2,55 metros de altura e est\u00e3o a 0,50 a 1 metro da linha lateral do campo.<\/li>\n<li>A rede de voleibol tem 1 metro de altura por 9,50 a 10 metros de largura.<\/li>\n<li>As Varetas de rede de voleibol devem ser flex\u00edveis e medir 1,8 metros de altura.<\/li>\n<li>As varetas est\u00e3o fixas na Rede nas linhas laterais do campo.<\/li>\n<li>A varetas serve para delimitar a \u00e1rea de cruzamento da bola por cima da rede.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Quantos_jogadores_tem_uma_equipa_de_Voleibol\"><\/span>Quantos jogadores t\u00eam uma equipa de Voleibol<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Uma equipa completa de voleibol \u00e9 composta por 12 jogadores, um treinador e at\u00e9 dois assistentes, um fisioterapeuta e um m\u00e9dico.<\/p>\n<p>O equipamento dos jogadores \u00e9 composto por camisa, cal\u00e7\u00f5es, meias e sapatos desportivos. Todos os jogadores devem usar uniformes iguais, exceto o libero. As camisas ser\u00e3o numeradas de 1 a 20. Os jogadores podem usar \u00f3culos ou lentes de contacto desde que assumam a responsabilidade pelos riscos.<\/p>\n<blockquote><p>NOTA: O treinador e o capit\u00e3o de equipa s\u00e3o respons\u00e1veis pela condu\u00e7\u00e3o de uma equipa de voleibol. O libero n\u00e3o pode ser o capit\u00e3o.<\/p><\/blockquote>\n<h2><span class=\"ez-toc-section\" id=\"Marcacao_de_Pontos_no_Voleibol\"><\/span>Marca\u00e7\u00e3o de Pontos no Voleibol<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Uma equipa marca pontos quando:<\/p>\n<ul>\n<li>Pode fazer a bola tocar no campo da equipa advers\u00e1ria;<\/li>\n<li>a equipa advers\u00e1ria joga a bola fora do campo de jogo;<\/li>\n<li>a equipa advers\u00e1ria comete uma falta\/viola\u00e7\u00e3o da regra;<\/li>\n<li>a equipa advers\u00e1ria \u00e9 penalizada.<\/li>\n<\/ul>\n<div>\n<dl id=\"attachment_996\">\n<dt><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-62262\" src=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2018\/01\/regras-voleibol.png\" alt=\"Regras do Voleibol: bola dentro e bola fora\" width=\"640\" height=\"360\" srcset=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2018\/01\/regras-voleibol.png 640w, https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2018\/01\/regras-voleibol-300x169.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/dt>\n<\/dl>\n<\/div>\n<h2><span class=\"ez-toc-section\" id=\"O_que_e_Jogada_no_Voleibol\"><\/span>O que \u00e9 Jogada no Voleibol?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Jogada no Voleibol s\u00e3o todas as a\u00e7\u00f5es que acontecem no jogo a partir do momento em que um Servi\u00e7o acontece at\u00e9 ao momento em que uma equipa marca um ponto. Cada novo Servi\u00e7o come\u00e7a uma nova Jogada.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quantos_Sets_tem_um_jogo_de_Voleibol\"><\/span>Quantos Sets tem um jogo de Voleibol?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>Um jogo de voleibol tem um m\u00ednimo de 3 conjuntos e um m\u00e1ximo de 5 conjuntos.<\/li>\n<li>Ganha um set no Voleibol a equipa que primeiro faz 25 pontos com uma diferen\u00e7a de 2 pontos para a outra equipa<\/li>\n<li>Se o jogo estiver empatado a 24-24, o set continuar\u00e1 para al\u00e9m dos 25 at\u00e9 que uma equipa possa abrir a diferen\u00e7a de 2 pontos e ganhar o set. Por exemplo, 26 a 24 ou 27 a 25 ou 28 a 26.<\/li>\n<li>A equipa que ganhar pela primeira vez 3 sets vai ganhar o jogo<\/li>\n<li>Em caso de empate 2-2, ser\u00e1 disputado o 5\u00ba set ou o Tie-Break de 15 pontos.<\/li>\n<li>Ganha o 5\u00ba set e come\u00e7a a equipa que soma os primeiros 15 pontos, com uma diferen\u00e7a m\u00ednima de 2 pontos.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/final-set-partida-voleibol.png\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/final-set-partida-voleibol.png\" alt=\"Final de Set no voleibol\" width=\"526\" height=\"206\" \/><\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Sobre_Sorteio_formacao_inicial_da_equipa_e_posicao_dos_jogadores_no_voleibol\"><\/span>Sobre Sorteio, forma\u00e7\u00e3o inicial da equipa e posi\u00e7\u00e3o dos jogadores no voleibol<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"Sorteio\"><\/span>Sorteio<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Antes da partida realiza-se um Sorteio para decidir quem vai retirar e quem receber\u00e1 o Sorteio, al\u00e9m de que lado do campo cada equipa estar\u00e1 no primeiro set. Se houver necessidade do quinto set, realizar-se-\u00e1 um novo sorteio.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Equipa_de_Voleibol\"><\/span>Equipa de Voleibol<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Cada equipa entrar\u00e1 no campo com 6 jogadores. A forma\u00e7\u00e3o inicial da equipa tamb\u00e9m indicar\u00e1 a posi\u00e7\u00e3o de cada jogador, que determina a ordem de rota\u00e7\u00e3o da equipa no primeiro set.<\/p>\n<blockquote><p>Aten\u00e7\u00e3o, aten\u00e7\u00e3o! A ordem de rota\u00e7\u00e3o determinada no in\u00edcio do Set deve ser mantida em todo o Set e s\u00f3 pode ser alterada no in\u00edcio de cada Set.<\/p><\/blockquote>\n<h3><span class=\"ez-toc-section\" id=\"Posicoes_e_Rotacao_no_Voleibol\"><\/span>Posi\u00e7\u00f5es e Rota\u00e7\u00e3o no Voleibol<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div>\n<dl id=\"attachment_400\">\n<dt><a href=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/posicoes-de-rotacao-no-voleibol.jpg\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/posicoes-de-rotacao-no-voleibol.jpg\" alt=\"Posi\u00e7\u00f5es de rota\u00e7\u00e3o no Voleibol\" width=\"516\" height=\"433\" \/><\/a><\/dt>\n<\/dl>\n<\/div>\n<ul>\n<li>Tr\u00eas jogadores devem formar a Zona de Ataque ou zona de rede, posi\u00e7\u00e3o 4 (rede esquerda), 3 (rede central) e 2 (rede direita ou sa\u00edda de rede).<\/li>\n<li>E 3 jogadores devem ocupar a Linha de Defesa ou Fundo do campo: 5 (inferior esquerdo), 6 (fundo central) e 1 (inferior direito).<\/li>\n<li>Depois de Servir jogadores pode mover-se livremente pelo campo.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Como_e_feita_Rotacao_no_Voleibol\"><\/span>Como \u00e9 feita Rota\u00e7\u00e3o no Voleibol?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A ordem de rota\u00e7\u00e3o no voleibol \u00e9 definida pela posi\u00e7\u00e3o inicial da equipa em cada conjunto.<\/p>\n<p>Quando uma equipa que recebe o Servi\u00e7o ganha a Jogada, ganha o direito de fazer o Servi\u00e7o, os seus jogadores t\u00eam de rodar uma posi\u00e7\u00e3o no sentido do tempo. O jogador que estava na posi\u00e7\u00e3o 2 (sa\u00edda da rede direita ou da rede), ir\u00e1 para a posi\u00e7\u00e3o 1, o jogador que estava na posi\u00e7\u00e3o 1, vai para a posi\u00e7\u00e3o 6, o jogador que estava na posi\u00e7\u00e3o 6, vai para a posi\u00e7\u00e3o 5 e assim at\u00e9 que todos rodem uma posi\u00e7\u00e3o.<\/p>\n<blockquote><p>\u00c9 importante! O jogador que ocupou a posi\u00e7\u00e3o 2 e avan\u00e7ou para a posi\u00e7\u00e3o 1 ser\u00e1 necessariamente o jogador respons\u00e1vel pelo pr\u00f3ximo Servi\u00e7o.<\/p><\/blockquote>\n<div>\n<dl id=\"attachment_401\">\n<dt><a href=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/rodizio-no-voleibol.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/rodizio-no-voleibol.jpg\" alt=\"Rota\u00e7\u00e3o no Voleibol\" width=\"600\" height=\"213\" \/><\/a><\/dt>\n<\/dl>\n<\/div>\n<h2><span class=\"ez-toc-section\" id=\"Faltas_de_Rotacao_no_Voleibol\"><\/span>Faltas de Rota\u00e7\u00e3o no Voleibol<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A falta de rota\u00e7\u00e3o \u00e9 quando um Servi\u00e7o \u00e9 realizado enquanto a equipa est\u00e1 fora de ordem de rota\u00e7\u00e3o. A equipa que cometer a Falta de Rota\u00e7\u00e3o ser\u00e1 punida com um ponto para a equipa advers\u00e1ria que tamb\u00e9m ganhar\u00e1 o direito de se retirar.<\/p>\n<p><a href=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/falta-rotacao-voleibol.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/falta-rotacao-voleibol.png\" alt=\"Falta de Rota\u00e7\u00e3o no Voleibol\" width=\"537\" height=\"204\" \/><\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Bola_fora_e_Toques_na_bola_no_Voleibol\"><\/span>Bola fora e Toques na bola no Voleibol<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h4><span class=\"ez-toc-section\" id=\"A_bola_e_considerada_fora_de_jogo_quando\"><\/span>A bola \u00e9 considerada fora de jogo quando:<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul>\n<li>a parte da bola que entra em contacto com o ch\u00e3o est\u00e1 fora das linhas que delimitam o campo;<\/li>\n<li>tocar em qualquer objeto que est\u00e1 fora do campo de jogo;<\/li>\n<li>toca na vareta, nas cordas de suporte da rede, nos postes ou nas partes da rede que est\u00e3o fora da \u00e1rea de jogo;<\/li>\n<li>atravessar completamente o espa\u00e7o abaixo da rede.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Toques_da_Equipa_na_bola\"><\/span>Toques da Equipa na bola<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Uma equipa pode realizar at\u00e9 3 toques na bola antes de envi\u00e1-la para a equipa advers\u00e1ria. Toque no Bloco n\u00e3o conta como um toque.<\/p>\n<blockquote><p>Quatro Toques<\/p>\n<p>A equipa que tiver mais de 3 toques cometer\u00e1 uma Falta.<\/p><\/blockquote>\n<h4><span class=\"ez-toc-section\" id=\"Dois_Toques\"><\/span>Dois Toques<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Um jogador n\u00e3o poder\u00e1 dar dois toques consecutivos na bola. Gravar a fechadura n\u00e3o conta como a primeira toque do jogador.<\/p>\n<blockquote><p>Toque Assistido<\/p>\n<p>N\u00e3o \u00e9 permitido apoiar-se noutro jogador ou objeto para bater na bola.<\/p><\/blockquote>\n<h4><span class=\"ez-toc-section\" id=\"Bola_Retida\"><\/span>Bola Retida<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>N\u00e3o \u00e9 permitido agarrar ou lan\u00e7ar a bola, deve ser atingida.<\/p>\n<p><a href=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/conducao-dois-toques-quatro-toques.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/conducao-dois-toques-quatro-toques.png\" alt=\"Bola Retida, dois toques e quatro toques no Voleibol\" width=\"469\" height=\"558\" \/><\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Invasao_sobre_a_Rede_no_Voleibol\"><\/span>Invas\u00e3o sobre a Rede no Voleibol<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>De acordo com as Regras de Voleibol, o bloqueador pode tocar a bola para al\u00e9m da rede, desde que n\u00e3o interfira antes ou durante o toque da bola do advers\u00e1rio.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Invasao_sob_a_Rede\"><\/span>Invas\u00e3o sob a Rede<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u00c9 permitido invadir o espa\u00e7o oposto sob a rede desde que:<\/p>\n<ul>\n<li>isto n\u00e3o interfere com o jogador advers\u00e1rio<\/li>\n<li>ficar com parte dos p\u00e9s na linha central<\/li>\n<\/ul>\n<div style=\"text-align: center;\">\n<dl id=\"attachment_1000\">\n<dt><a href=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/invasao-sobre-rede-voleibol.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/invasao-sobre-rede-voleibol.png\" alt=\"Invas\u00e3o sobre a rede no Voleibol\" width=\"575\" height=\"206\" \/><\/a><\/dt>\n<\/dl>\n<\/div>\n<h2><span class=\"ez-toc-section\" id=\"Contacto_com_a_Rede_de_Voleibol_Toque_na_rede\"><\/span>Contacto com a Rede de Voleibol (Toque na rede)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>O contacto do jogador com a rede, entre as varetas, \u00e9 sempre considerado ausente se durante uma a\u00e7\u00e3o de jogo<\/li>\n<li>Quando a bola toca na rede e promove um contacto do jogo com a rede, n\u00e3o \u00e9 considerada falta<\/li>\n<li>O toque dos postes, dos cabos da rede ou da pr\u00f3pria rede n\u00e3o \u00e9 considerado em falta se for feito ap\u00f3s os limites das varetas.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Sobre_o_Servico_no_Voleibol\"><\/span>Sobre o Servi\u00e7o no Voleibol<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h4><span class=\"ez-toc-section\" id=\"Servico_e_faltas_de_Servico\"><\/span>Servi\u00e7o e faltas de Servi\u00e7o<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul>\n<li>O primeiro servi\u00e7o \u00e9 definido por sorteio<\/li>\n<li>O pr\u00f3ximo servi\u00e7o ser\u00e1 feito pela equipa que ganhar a Jogada<\/li>\n<li>A equipa que come\u00e7ou a receber o Servi\u00e7o no primeiro set come\u00e7ar\u00e1 o segundo set com o servi\u00e7o, e continuar\u00e1 a altern\u00e2ncia a cada set<\/li>\n<li>O Servi\u00e7o deve ser sempre autorizado pelo \u00e1rbitro.<\/li>\n<li>O jogador que vai Servir n\u00e3o pode pisar na linha de tr\u00e1s do seu campo antes de executar o Servi\u00e7o<\/li>\n<\/ul>\n<div style=\"text-align: center;\">\n<dl id=\"attachment_1001\">\n<dt><a href=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/autorizacao-saque-voleibol.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/autorizacao-saque-voleibol.png\" alt=\"Autoriza\u00e7\u00e3o do Servi\u00e7o no Voleibol\" width=\"529\" height=\"205\" \/><\/a><\/dt>\n<\/dl>\n<\/div>\n<h2><span class=\"ez-toc-section\" id=\"Sao_Faltas_de_Ataque_no_voleibol\"><\/span>S\u00e3o Faltas de Ataque no voleibol:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>Corte a bola dentro do espa\u00e7o de jogo do oponente<\/li>\n<li>Quando um jogador de Fundo (posi\u00e7\u00f5es 5, 6 1) corta a bola enquanto est\u00e1 acima da gama superior da Rede.<\/li>\n<li>Ataque n\u00e3o \u00e9 permitido atacar o Servi\u00e7o do oponente<\/li>\n<li>Libero corta a bola acima do alcance superior da Rede.<\/li>\n<li>Se o Libero estiver na Zona de Ataque e fizer uma Distribui\u00e7\u00e3o a usar o &#8220;Passe por cima&#8221;, os seus companheiros de equipa n\u00e3o podem Atacar a bola acima da gama superior da Rede.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Sao_faltas_do_Bloco_de_Voleibol\"><\/span>S\u00e3o faltas do Bloco de Voleibol:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>Blocar o Servi\u00e7o do oponente;<\/li>\n<li>Toque na bola antes que o seu oponente execute o ataque;<\/li>\n<li>Um jogador que esteja na Zona ou Linha de Defesa (posi\u00e7\u00f5es 5, 6 e 1) ou um Libero executa um Ataque;<\/li>\n<li>Blocar a bola fora da Vareta de Rede<\/li>\n<li>Se libero tentar executar um Bloco, mesmo que n\u00e3o toque na bola.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/falta-de-bloqueio-voleibol.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/falta-de-bloqueio-voleibol.png\" alt=\"Faltas de Bloco no Voleibol\" width=\"525\" height=\"203\" \/><\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Pedido_de_Tempo_e_Substituicoes_no_Voleibol\"><\/span>Pedido de Tempo e Substitui\u00e7\u00f5es no Voleibol<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Cada equipa tem direito a dois pedidos de tempo e 6 substitui\u00e7\u00f5es por Set. O pedido de tempo pode ser feito pelo treinador ou, na aus\u00eancia do treinador, pelo Capit\u00e3o da equipa.<\/p>\n<div style=\"text-align: center;\">\n<dl id=\"attachment_407\">\n<dt><a href=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/tempo-e-substituicao-no-voleibol.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2017\/02\/tempo-e-substituicao-no-voleibol.png\" alt=\"Pedido de Tempo e Substitui\u00e7\u00e3o no Voleibol\" width=\"600\" height=\"249\" \/><\/a><\/dt>\n<\/dl>\n<\/div>\n<h2><span class=\"ez-toc-section\" id=\"Pausas_e_mudanca_de_Campo_no_Voleibol\"><\/span>Pausas e mudan\u00e7a de Campo no Voleibol<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>De acordo com as Regras de Voleibol, o intervalo \u00e9 o tempo entre os sets e os \u00faltimos 3 minutos. Durante o intervalo, o campo \u00e9 alterado, exceto no Tie-Break. No Tie-Break a mudan\u00e7a de campo \u00e9 feita sem intervalo quando a primeira equipa chega aos 8 pontos.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Regras_para_o_voleibol_libero\"><\/span>Regras para o voleibol libero:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>Cada equipa tem direito \u00e0 lista 2 Liberos<\/li>\n<li>Cada equipa s\u00f3 pode ter 1 Libero a jogar em campo<\/li>\n<li>O Libero deve usar uniforme com cor dominante diferente dos outros jogadores da sua equipa.<\/li>\n<li>O Libero n\u00e3o pode Servir, blocar, tentar blocar ou atacar a bola enquanto est\u00e1 acima da gama superior da Rede<\/li>\n<li>Libero s\u00f3 pode substituir jogadores que est\u00e3o a ocupar a Zona de Defesa (posi\u00e7\u00f5es 5, 6 e 1)<\/li>\n<li>Se o Libero na Zona de Ataque fizer um Distribui\u00e7\u00e3o a usar o &#8220;Passe por cima&#8221;, os seus companheiros de equipa n\u00e3o ser\u00e3o capazes de atacar acima do alcance superior da Rede.<\/li>\n<li>Na Zona de Defesa, L\u00edbero pode fazer Distribui\u00e7\u00f5es de qualquer forma.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Video_sobre_as_regras_do_voleibol\"><\/span>V\u00eddeo sobre as regras do voleibol<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>V\u00eddeo: <a href=\"https:\/\/youtu.be\/CQXEUPoA2_Y\" target=\"_blank\" rel=\"noopener noreferrer\">Regras do Voleibol<\/a><\/li>\n<\/ul>\n<p><!--Ads9--><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Mais_conteudo_de_voleibol\"><\/span>Mais conte\u00fado de voleibol<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/gestos-tecnicos-voleibol\/\">Gestos T\u00e9cnicos do Voleibol<\/a><\/li>\n<li><a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/origem-historia-voleibol\/\">Origem do Voleibol<\/a><\/li>\n<li><a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/curso-voleibol-gratis\/\">Curso de Voleibol Online Gr\u00e1tis<\/a><\/li>\n<li><a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-basicas-voleibol\/\">Regras B\u00e1sicas do Voleibol<\/a><\/li>\n<li><a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-libero-voleibol\/\">Regras para L\u00edbero de Voleibol<\/a><\/li>\n<li><a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/campo-voleibol-oficial\/\">Campo de Voleibol Oficial<\/a><\/li>\n<li><a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/fundamentos-do-voleibol\/\">Fundamentos T\u00e9cnicos do Voleibol<\/a><\/li>\n<li><a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-oficiais-voleibol\/\">Regras Oficiais do Voleibol<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Introdu\u00e7\u00e3o: Regras do Voleibol Descubra todas as regras do Voleibol e tire todas as suas d\u00favidas com esse artigo ilustrado e explicativo que o Blog Dicas Educa\u00e7\u00e3o F\u00edsica preparou com muito carinho para voc\u00ea que gosta de jogar Voleibol. Chega de conte\u00fado raso que n\u00e3o explicada quase nada, aqui, voc\u00ea vai aprender todas as regras&hellip;&nbsp;<a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-voleibol\/\" rel=\"bookmark\">Ler mais &raquo;<span class=\"screen-reader-text\">Regras do VOLEIBOL Ilustradas<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[401,390],"tags":[],"class_list":["post-62251","post","type-post","status-publish","format-standard","hentry","category-voleibol-pt-pt","category-modalidades-desportes"],"_links":{"self":[{"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/posts\/62251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/comments?post=62251"}],"version-history":[{"count":0,"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/posts\/62251\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/media?parent=62251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/categories?post=62251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/tags?post=62251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}