{"id":191121,"date":"2019-09-11T20:38:49","date_gmt":"2019-09-11T23:38:49","guid":{"rendered":"https:\/\/www.dicaseducacaofisica.info\/golpes-jiu-jitsu\/"},"modified":"2022-07-01T18:04:37","modified_gmt":"2022-07-01T21:04:37","slug":"golpes-jiu-jitsu","status":"publish","type":"post","link":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/","title":{"rendered":"GOLPES DO JIU-JITSU: CONHE\u00c7A AS PRINCIPAIS FINALIZA\u00c7\u00d5ES"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/#CONHECA_OS_GOLPES_DO_JIU-JITSU\" >CONHE\u00c7A OS GOLPES DO JIU-JITSU<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/#GOLPE_HADAKA_JIME_NO_JIU-JITSU\" >GOLPE HADAKA JIME NO JIU-JITSU<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/#A_MONTADA_NO_JIU-JITSU\" >A MONTADA NO JIU-JITSU<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/#GOLPE_CHAVE_DE_BRACO_NO_JIU-JITSU\" >GOLPE CHAVE DE BRA\u00c7O NO JIU-JITSU<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/#GOLPE_ARM-LOCK_NO_JIU-JITSU\" >GOLPE ARM-LOCK NO JIU-JITSU<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/#GOLPE_GUILHOTINA_NO_JIU-JITSU\" >GOLPE\u00a0 GUILHOTINA NO JIU-JITSU<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/#GOLPE_JOELHO_NA_BARRIGA_NO_JIU-JITSU\" >GOLPE JOELHO NA BARRIGA NO JIU-JITSU<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/#A_HORA_DA_FINALIZACAO_NO_JIU-JITSU\" >A HORA DA FINALIZA\u00c7\u00c3O NO JIU-JITSU<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/#VIDEO_TECNICAS_DE_JIU-JITSU_PARA_INICIANTES_E_GRADUADOS\" >V\u00cdDEO: T\u00c9CNICAS DE JIU-JITSU PARA INICIANTES E GRADUADOS<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/#MAIS_CONTEUDOS_SOBRE_LUTAS\" >MAIS CONTE\u00daDOS SOBRE LUTAS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/#CONCLUSAO\" >CONCLUS\u00c3O<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"CONHECA_OS_GOLPES_DO_JIU-JITSU\"><\/span>CONHE\u00c7A OS GOLPES DO JIU-JITSU<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Todos os desportos de combate t\u00eam suas t\u00e9cnicas e golpes caracter\u00edsticos. Alguns golpes j\u00e1 viraram frases de efeito e marca registrada do <a href=\"https:\/\/www.dicaseducacaofisica.info\/lutas\/jiu-jitsu\/\">jiu-jitsu<\/a>, que \u00e9 o caso do \u201cmata-le\u00e3o\u201d e da \u201cchave de bra\u00e7o\u201d.<\/p>\n<p>Muitos iniciantes t\u00eam dificuldades em entender alguns golpes, ou mesmo em quais s\u00e3o os golpes, pois, existe uma variedade deles por a\u00ed. Afinal, saber um pouco mais sobre o desporto que pratica n\u00e3o \u00e9 nada de mal.<\/p>\n<p>Conhecer e aplicar da maneira certa apenas se consegue a treinar muito e a praticar. Eles podem ser a diferen\u00e7a entre perder ou vender uma luta.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"GOLPE_HADAKA_JIME_NO_JIU-JITSU\"><\/span>GOLPE HADAKA JIME NO JIU-JITSU<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Aposto que voc\u00ea nunca ouviu esse nome, n\u00e3o \u00e9? Na verdade, mesmo que voc\u00ea diga que n\u00e3o, esse golpe \u00e9 muito conhecido e com certeza j\u00e1 ouviu falar dele.<\/p>\n<p>Esse \u00e9 o famoso e temido Mata Le\u00e3o, um golpe de finaliza\u00e7\u00e3o que consistem em estrangular o oponente pelas costas, a usar os b\u00edceps para encobrir o pesco\u00e7o do advers\u00e1rio.<\/p>\n<blockquote><p>Veja tamb\u00e9m &#8211; <a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-jiu-jitsu\/\">Regras do Jiu-Jitsu<\/a><\/p><\/blockquote>\n<h2><span class=\"ez-toc-section\" id=\"A_MONTADA_NO_JIU-JITSU\"><\/span>A MONTADA NO JIU-JITSU<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-8296 size-full\" src=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2019\/09\/golpes-jiu-jitsu.jpg\" alt=\"Conhe\u00e7a os Golpes do Jiu-Jitsu: hadaka jime, montada, chave de bra\u00e7o, arm-lock, guilhotina, joelho na barriga e a hora da finaliza\u00e7\u00e3o.\" width=\"640\" height=\"426\" srcset=\"https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2019\/09\/golpes-jiu-jitsu.jpg 640w, https:\/\/www.dicaseducacaofisica.info\/wp-content\/uploads\/2019\/09\/golpes-jiu-jitsu-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Pode ser criancice da minha parte, mas, n\u00e3o brinco quando falo que existe um alto grau de duplo sentido fixado em cada palavra sobre este golpe de artes marciais. Por\u00e9m, tentarei amenizar.<\/p>\n<p>Trata-se de um golpe de imobiliza\u00e7\u00e3o onde o objetivo \u00e9 manter os joelhos e p\u00e9s do advers\u00e1rio no ch\u00e3o, esteja ele de frente, lado ou de costas. Esse golpe apenas pode ser validado se o golpe aplicado apenas ocorrer sobre um dos bra\u00e7os do oponente.<\/p>\n<p>Se acontecer de ser os dois bra\u00e7os afetados pelo golpe, o mesmo ser\u00e1 invalidade e o lutador n\u00e3o receber\u00e1 pontos.<\/p>\n<blockquote><p>Veja tamb\u00e9m &#8211;\u00a0 <a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/faixas-jiu-jitsu\/\">Faixas e Gradua\u00e7\u00e3o no Jiu-jitsu<\/a><\/p><\/blockquote>\n<h2><span class=\"ez-toc-section\" id=\"GOLPE_CHAVE_DE_BRACO_NO_JIU-JITSU\"><\/span>GOLPE CHAVE DE BRA\u00c7O NO JIU-JITSU<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Esse \u00e9 um dos golpes mais conhecidos, mesmo por quem n\u00e3o pratica o desporto. Sua fama se deve a men\u00e7\u00e3o em outros estilos de competi\u00e7\u00f5es de combate, como luta livre e UFC.<\/p>\n<p>Basicamente, a <a href=\"https:\/\/youtu.be\/OUAsRYtU05c\" target=\"_blank\" rel=\"noopener\">Chave de Bra\u00e7o<\/a> consistem em agarrar o bra\u00e7o do oponente com as pernas e segurar firme os punhos com a m\u00e3o, como uma alavanca, por\u00e9m, com o quadril at\u00e9 que o oponente desiste ou seja finalizado.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"GOLPE_ARM-LOCK_NO_JIU-JITSU\"><\/span>GOLPE ARM-LOCK NO JIU-JITSU<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Vamos falar do irm\u00e3o pr\u00f3ximo da chave de bra\u00e7o, por\u00e9m, \u00e9 mais perigoso e arriscado, pois, o seu advers\u00e1rio pode acabar com o bra\u00e7o quebrado. Por isso, pense antes de apelar para um golpe de jiu-jitsu t\u00e3o perigoso.<\/p>\n<p>Nesses golpes, o lutador agarra o bra\u00e7o do advers\u00e1rio com as suas pernas, agarra o punho com as m\u00e3os e realiza uma alavanca com o quadril com for\u00e7a at\u00e9 finalizar seu oponente.<\/p>\n<blockquote><p>Veja tamb\u00e9m &#8211; <a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/regras-do-mma\/\">Regras do MMA<\/a><\/p><\/blockquote>\n<h2><span class=\"ez-toc-section\" id=\"GOLPE_GUILHOTINA_NO_JIU-JITSU\"><\/span>GOLPE\u00a0 GUILHOTINA NO JIU-JITSU<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Calma a\u00ed, ningu\u00e9m vai cortar a cabe\u00e7a de ningu\u00e9m com uma l\u00e2mina afiada. Este golpe de jiu-jitsu trata-se apenas de um golpe onde o lutador envolve um de seus bra\u00e7os na cabe\u00e7a do oponente enquanto ele est\u00e1 em guarda.<\/p>\n<p>O outro bra\u00e7o, completa e fecha a chave. Por fim, utiliza-se o quadril para finalizar o advers\u00e1rio a exercer press\u00e3o sobre ele a pressionar sua cabe\u00e7a.<\/p>\n<blockquote><p>Veja tamb\u00e9m &#8211; <a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/tudo-sobre-jiu-jitsu\/\">Tudo Sobre Jiu-Jitsu: Hist\u00f3ria, Regras, Golpes e Faixas<\/a><\/p><\/blockquote>\n<h2><span class=\"ez-toc-section\" id=\"GOLPE_JOELHO_NA_BARRIGA_NO_JIU-JITSU\"><\/span>GOLPE JOELHO NA BARRIGA NO JIU-JITSU<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Vamos para outros golpes de jiu-jitsu onde um dos lutadores est\u00e1 por cima do outro, neste caso, o golpe joelho na barriga ocorre quando um dos lutadores est\u00e1, literalmente, por cima do outro.<\/p>\n<p>O lutador que est\u00e1 sobre o oponente ca\u00eddo coloca o joelho na barriga dele, a manter a outra perna sempre flexionada e os p\u00e9s no ch\u00e3o. Para completar, segura-se a gola, os bra\u00e7os ou a faixa do oponente. O objetivo \u00e9 domin\u00e1-lo<\/p>\n<h2><span class=\"ez-toc-section\" id=\"A_HORA_DA_FINALIZACAO_NO_JIU-JITSU\"><\/span>A HORA DA FINALIZA\u00c7\u00c3O NO JIU-JITSU<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Essa parte \u00e9 crucial em uma luta. O lutador deve fazer com que o advers\u00e1rio desista. Para isso, \u00e9 preciso um golpe perfeitamente executado, geralmente uma tor\u00e7\u00e3o ou estrangulamento imposs\u00edvel de se escapar.<\/p>\n<p>Quando o lutar ouvir o belo som de 3 tapinhas no tatame, este \u00e9 declarado o vencedor.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"VIDEO_TECNICAS_DE_JIU-JITSU_PARA_INICIANTES_E_GRADUADOS\"><\/span>V\u00cdDEO: T\u00c9CNICAS DE JIU-JITSU PARA INICIANTES E GRADUADOS<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"nv-iframe-embed\"><iframe title=\"7 T\u00e9cnicas de Jiu Jitsu Para Iniciantes e Graduados\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/ulfCXnwDu_o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<h2><span class=\"ez-toc-section\" id=\"MAIS_CONTEUDOS_SOBRE_LUTAS\"><\/span>MAIS CONTE\u00daDOS SOBRE LUTAS<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><strong>\u21d2<\/strong> <a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-muay-thai\/\">Golpes B\u00e1sicos do Muay Thai<\/a><\/p>\n<p><strong>\u21d2<\/strong> <a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/historia-jiu-jitsu\/\">A Hist\u00f3ria do Jiu-Jitsu no Mundo<\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"CONCLUSAO\"><\/span>CONCLUS\u00c3O<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Os golpes de jiu-jitsu devem ser muito bem praticados para evitar que situa\u00e7\u00f5es graves acabem a acontecer durante as lutas. Um lutador inexperiente em um golpe, ao tentar aplica-lo, pode ferir gravemente seu advers\u00e1rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CONHE\u00c7A OS GOLPES DO JIU-JITSU Todos os desportos de combate t\u00eam suas t\u00e9cnicas e golpes caracter\u00edsticos. Alguns golpes j\u00e1 viraram frases de efeito e marca registrada do jiu-jitsu, que \u00e9 o caso do \u201cmata-le\u00e3o\u201d e da \u201cchave de bra\u00e7o\u201d. Muitos iniciantes t\u00eam dificuldades em entender alguns golpes, ou mesmo em quais s\u00e3o os golpes, pois,&hellip;&nbsp;<a href=\"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/golpes-jiu-jitsu\/\" rel=\"bookmark\">Ler mais &raquo;<span class=\"screen-reader-text\">GOLPES DO JIU-JITSU: CONHE\u00c7A AS PRINCIPAIS FINALIZA\u00c7\u00d5ES<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_page_generator_pro_exclude":false,"_page_generator_pro_group":0,"_page_generator_pro_index":0,"footnotes":""},"categories":[455,448],"tags":[],"class_list":["post-191121","post","type-post","status-publish","format-standard","hentry","category-jiu-jitsu-pt-pt","category-lutas-pt-pt"],"_links":{"self":[{"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/posts\/191121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/comments?post=191121"}],"version-history":[{"count":0,"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/posts\/191121\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/media?parent=191121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/categories?post=191121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dicaseducacaofisica.info\/pt-pt\/wp-json\/wp\/v2\/tags?post=191121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}